{"id":1185,"date":"2023-08-25T13:29:05","date_gmt":"2023-08-25T13:29:05","guid":{"rendered":"https:\/\/boccard.com\/?page_id=1185"},"modified":"2026-03-04T15:07:05","modified_gmt":"2026-03-04T15:07:05","slug":"vision-missions-valeurs","status":"publish","type":"page","link":"https:\/\/www.boccard.com\/fr\/adn-boccard\/vision-missions-valeurs\/","title":{"rendered":"Vision, Missions &amp; Valeurs"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1185\" class=\"elementor elementor-1185\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0bee075 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0bee075\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a9f72ce\" data-id=\"a9f72ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0ab5ab5 elementor-align-left elementor-widget elementor-widget-breadcrumbs\" data-id=\"0ab5ab5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.boccard.com\/fr\/\">Accueil<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b54e19 elementor-widget elementor-widget-heading\" data-id=\"6b54e19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">L'ADN Boccard<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2e268a9 titre_marches elementor-widget elementor-widget-heading\" data-id=\"2e268a9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Nos <b>Valeurs<\/b><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cba319b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cba319b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9283fc5\" data-id=\"9283fc5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-082ba6a elementor-widget elementor-widget-heading\" data-id=\"082ba6a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Notre vision<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3e66ed quote elementor-widget elementor-widget-text-editor\" data-id=\"f3e66ed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"p1\"><em>Leader des solutions industrielles digitales pleinement int\u00e9gr\u00e9es<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d795c45\" data-id=\"d795c45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd8ef53 photoo elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"cd8ef53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1709\" src=\"https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/10\/DSC3897-scaled-1.jpg\" class=\"attachment-full size-full wp-image-54250\" alt=\"\" srcset=\"https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/10\/DSC3897-scaled-1.jpg 2560w, https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/10\/DSC3897-scaled-1-300x200.jpg 300w, https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/10\/DSC3897-scaled-1-1024x684.jpg 1024w, https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/10\/DSC3897-scaled-1-768x513.jpg 768w, https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/10\/DSC3897-scaled-1-1536x1025.jpg 1536w, https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/10\/DSC3897-scaled-1-2048x1367.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3957046 elementor-widget elementor-widget-spacer\" data-id=\"3957046\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de1b437 elementor-widget elementor-widget-heading\" data-id=\"de1b437\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bruno &amp; PATRICK BOCCARD<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64d4f3c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"64d4f3c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31b3722\" data-id=\"31b3722\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-097c96b elementor-widget elementor-widget-heading\" data-id=\"097c96b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Notre mission<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-600fd2b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"600fd2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d953f08 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d953f08\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-796466a\" data-id=\"796466a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a01599f elementor-widget elementor-widget-image\" data-id=\"a01599f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"500\" src=\"https:\/\/www.boccard.com\/wp-content\/uploads\/2026\/03\/Boccard-Life-Energy-Solutions-Caring-For-People-Planet.png\" class=\"attachment-full size-full wp-image-86308\" alt=\"\" srcset=\"https:\/\/www.boccard.com\/wp-content\/uploads\/2026\/03\/Boccard-Life-Energy-Solutions-Caring-For-People-Planet.png 1920w, https:\/\/www.boccard.com\/wp-content\/uploads\/2026\/03\/Boccard-Life-Energy-Solutions-Caring-For-People-Planet-300x78.png 300w, https:\/\/www.boccard.com\/wp-content\/uploads\/2026\/03\/Boccard-Life-Energy-Solutions-Caring-For-People-Planet-1024x267.png 1024w, https:\/\/www.boccard.com\/wp-content\/uploads\/2026\/03\/Boccard-Life-Energy-Solutions-Caring-For-People-Planet-768x200.png 768w, https:\/\/www.boccard.com\/wp-content\/uploads\/2026\/03\/Boccard-Life-Energy-Solutions-Caring-For-People-Planet-1536x400.png 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fbbc8b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fbbc8b3\" data-element_type=\"section\" data-e-type=\"section\" id=\"nos-valeurs\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-91daade\" data-id=\"91daade\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d686cb7 elementor-widget elementor-widget-heading\" data-id=\"d686cb7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos valeurs<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc332f1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"cc332f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75c954c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75c954c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a44fb43\" data-id=\"a44fb43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4db85f3 elementor-widget elementor-widget-accordion\" data-id=\"4db85f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8141\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-8141\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Entreprendre avec audace et t\u00e9nacit\u00e9<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8141\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-8141\"><p class=\"bloc\" id=\"entreprendre-avec-audace\" >Pour Joseph Boccard, toute prise d\u2019initiative, si hardie soit elle, n\u2019a qu\u2019une seule issue possible : le succ\u00e8s. Un \u00e9tat d\u2019esprit dont h\u00e9rite son fils Francisque Boccard, qui, en accentuant le virage de l\u2019entreprise dans l\u2019univers de la tuyauterie industrielle, lui conf\u00e8re une stature nationale.<\/p>\n\n<div class=\"carrebleu\">\n<p class=\"nom\">Joseph Boccard<\/p>\n<p class=\"citation\">Nous avons toujours dit oui aux opportunit\u00e9s<\/p>\n\n<\/div>\n<div class=\"imge_1\"><\/div>\n<p class=\"bloc\">\u00c0 leur tour, Alain et Jean-Luc Boccard \u00e9largissent les horizons en relevant le pari d\u2019accompagner les clients \u00e0 l\u2019international et en partant \u00e0 la conqu\u00eate de nouveaux march\u00e9s, avec des \u00e9quipes qui ont carte blanche pour d\u00e9velopper et g\u00e9rer les affaires en local.<\/p>\nDans leur sillage, Bruno et Patrick Boccard acc\u00e9l\u00e8rent et approfondissent la diversification m\u00e9tiers, march\u00e9s et g\u00e9ographies \u00e0 travers une nouvelle vision strat\u00e9gique \u2013 celle d\u2019ensemblier industriel \u2013 le d\u00e9veloppement de l\u2019intimacy client et la confiance manifest\u00e9e aux collaborateurs r\u00e9sum\u00e9s en ces termes : \u201cAlliance for success \u00bb.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8142\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-8142\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u00c9voluer avec agilit\u00e9<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8142\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-8142\"><p id=\"evoluer-avec-agilite\" class=\"bloc\">Un nombre intouchable* que nos \u00e9quipes ont finalement atteint pour r\u00e9pondre au d\u00e9fi lanc\u00e9 par Chobani : construire en moins d\u2019un an la plus grande usine de yaourt au monde (326 jours).<\/p>\n\u00c0 l\u2019ampleur du chantier \u2013 un complexe de 93 000 m\u00b2 sur un terrain de 81 hectares \u2013 s\u2019ajoute la modularit\u00e9 des installations dont il faut garantir l\u2019extensibilit\u00e9 et l\u2019adaptation \u00e0 la production de nouvelles gammes de yaourt.\n<div class=\"carrebleu\">\n<p class=\"nom2\">326<\/p>\n<p class=\"citation\">Le nombre intouchable<\/p>\n\n<\/div>\n<div class=\"imge_2\"><\/div>\n<p class=\"bloc\">Une telle complexit\u00e9 impliquait de mettre en \u0153uvre une approche design-to-build, o\u00f9 les phases de conception et de construction sont conduites en parall\u00e8le, afin de r\u00e9duire les d\u00e9lais de livraison et minimiser les risques. La r\u00e9activit\u00e9 et la coordination de Boccard Food &amp; Beverage, de Boccard Food \u00e0 Montauban, de Boccard Process Vessels \u00e0 Roanne et de Boccard Life Sciences \u00e0 Houston ont \u00e9t\u00e9 d\u00e9cisives pour ajuster le curseur dans ce qui fut un marathon couru \u00e0 l\u2019allure d\u2019un sprint !<\/p>\n<p style=\"color: #34bef1; font-size: 13px; display: block; font-weight: 500;\">* Un nombre intouchable est un entier naturel qui ne peut pas \u00eatre exprim\u00e9 comme la somme de tous les diviseurs stricts d\u2019un entier donn\u00e9.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8143\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-8143\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Construire avec fiabilit\u00e9<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8143\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-8143\"><p id=\"construire-avec-fiabilite\" class=\"bloc\">Cinquante ann\u00e9es de collaboration rythm\u00e9es par de nombreux chantiers initi\u00e9s au lendemain du choc p\u00e9trolier, lorsque la France entreprend la construction de centrales nucl\u00e9aires afin d\u2019assurer son ind\u00e9pendance \u00e9nerg\u00e9tique. D\u00e8s 1972, Boccard SA intervient sur le chantier de la centrale du Bugey, o\u00f9 est pr\u00e9vue la mise en service de quatre tranches de 900 MW.<\/p>\n\n<div class=\"carrebleu\">\n<p class=\"nom2\">50<\/p>\n<p class=\"citation\">Ann\u00e9es d&rsquo;exp\u00e9rience<\/p>\n\n<\/div>\n<div class=\"imge_3\"><\/div>\n<p class=\"bloc\">Ces derni\u00e8res, qualifi\u00e9es de pr\u00e9-s\u00e9ries, ont permis de structurer et consolider les contrats-programmes CP1 et CP2, soit 28 tranches construites entre 1974 et 1983. Leur d\u00e9lai de mise en service am\u00e8ne Boccard \u00e0 d\u00e9velopper les comp\u00e9tences de ses \u00e9quipes en s\u2019appropriant les contraintes sp\u00e9cifiques au nucl\u00e9aire : tra\u00e7abilit\u00e9 des montages et des interventions, contr\u00f4le qualit\u00e9, assurance qualit\u00e9 ind\u00e9pendante, propret\u00e9, complexit\u00e9 des installations, contrainte de radioprotection.\n\nL\u2019expertise m\u00e9tier continuellement acquise permet \u00e0 Boccard d\u2019accompagner EDF dans la r\u00e9alisation des programmes suivants qui introduiront de nouveaux paliers (P4, P\u20194 puis N4) ainsi qu\u2019une nouvelle g\u00e9n\u00e9ration de r\u00e9acteur (EPR). Aujourd\u2019hui encore, Boccard reste aux cot\u00e9s d\u2019EDF un acteur de premier plan dans la construction des EPR au Royaume-Uni et en Inde.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8144\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-8144\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">S'engager avec passion<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8144\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-8144\"><p class=\"quotetwo\">La livraison au client constitue toujours un moment particulier, o\u00f9 la satisfaction d\u2019avoir fait \u0153uvre utile et la saveur qui en d\u00e9coule demeurent. Suivre un projet de A \u00e0 Z et composer avec ses sp\u00e9cificit\u00e9s est aussi une chance.<\/p>\nNous avons obtenu un premier contrat sur le site de La Hague, d\u2019une dur\u00e9e initiale de 20 mois, pour finalement 8 ans cons\u00e9cutifs de pr\u00e9sence sur le site suite \u00e0 l\u2019obtention de contrats suppl\u00e9mentaires pour plusieurs ateliers.\n\nJ\u2019ai eu la chance d\u2019\u00eatre le premier \u00e0 arriver sur le site et le dernier \u00e0 le quitter ! C\u2019est l\u00e0 pour moi est une marque de confiance et de reconnaissance. Ceci prouve que, chez Boccard, les perspectives sont nombreuses, pour peu que l\u2019on soit motiv\u00e9. Car l\u2019entreprise cherche avant tout des personnes qui s\u2019engagent pour sa p\u00e9rennit\u00e9.\u00a0\u00bb\n<p class=\"nameautre\"><span>Claude Goyer <\/span>\u2022 Directeur de projet<\/p>\n<p class=\"fourty\">40 ans de service chez boccard<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8145\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-8145\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Rechercher l'excellence<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8145\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-8145\"><p id=\"rechercher-lexcellence\" class=\"bloc\">Depuis les ann\u00e9es 1980, nous avons pris conscience du potentiel des outils digitaux dans la planification et la gestion de la pr\u00e9fabrication.<\/p>\n\n<div class=\"carrebleu\">\n<p class=\"nom\">excellence<\/p>\n<p class=\"citation\">L\u2019excellence, c\u2019est d\u2019abord\nun \u00e9tat d\u2019esprit<\/p>\n\n<\/div>\n<div class=\"imge_4\"><\/div>\n<p class=\"bloc\">Des diff\u00e9rents d\u00e9veloppements conduits en interne est issu un syst\u00e8me propri\u00e9taire, BocTrack, qui a d\u2019abord \u00e9t\u00e9 d\u00e9ploy\u00e9 sur les grands projets de pr\u00e9fabrication avant d\u2019\u00eatre \u00e9tendu \u00e0 l\u2019ensemble de nos p\u00e9rim\u00e8tres m\u00e9tiers : ing\u00e9nierie, construction et maintenance. BocTrack est aujourd\u2019hui notre outil de gestion de production assist\u00e9e par ordinateur (CAPM) complet qui permet de contr\u00f4ler et de ma\u00eetriser l\u2019ex\u00e9cution de nos projets, depuis la r\u00e9ception des plans isom\u00e9triques jusqu\u2019au montage, tout en int\u00e9grant les exigences sp\u00e9cifi\u00e9es par nos clients en amont.\n\nNos clients, via l\u2019acc\u00e8s \u00e0 leur espace s\u00e9curis\u00e9, peuvent suivre \u00e0 tout moment l\u2019avancement de leur projet gr\u00e2ce \u00e0 des reportings actualis\u00e9s en temps r\u00e9el. Un support pr\u00e9cieux pour Ecopetrol, que nous assistons dans le management de la fabrication et le montage du projet \u201cEnergie et Vapeur\u201d sur sa raffinerie de Barrancabermeja, en Colombie.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8146\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-8146\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Grandir avec bienveillance<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8146\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-8146\"><p id=\"grandir-avec-bienceillance\" class=\"bloc\">D\u00e9velopper les comp\u00e9tences des femmes et des hommes pour que chacun gagne en autonomie, en assurance et en expertise, est une cl\u00e9 majeure de la r\u00e9ussite des projets que nous conduisons. La diversit\u00e9 g\u00e9ographique de nos implantations, combin\u00e9e \u00e0 la pluralit\u00e9 des march\u00e9s que nous adressons, constitue pour nos collaborateurs un formidable tremplin pour construire leur carri\u00e8re. BocMobility a vocation \u00e0 les accompagner dans leur choix d\u2019\u00e9volution.<\/p>\n\n<div class=\"carrebleu\">\n<p class=\"nom\">\u00e9voluer<\/p>\n<p class=\"citation\">\u00c9voluer signifie\napprendre des autres<\/p>\n\n<\/div>\n<div class=\"imge_5\"><\/div>\n<p class=\"bloc\">Chez Boccard, \u00e9voluer ne signifie pas uniquement changer de poste ou d\u2019environnement mais aussi apprendre des autres. L\u2019expertise se nourrit d\u2019exp\u00e9riences communes et partag\u00e9es entre diff\u00e9rentes g\u00e9n\u00e9rations \u00e0 l\u2019image de Dominique, Antoine et David De Rouck. Boccard Academy, qui organise le d\u00e9veloppement des comp\u00e9tences, favorise cette transmission des savoirs \u00e0 l\u2019\u00e9chelle de l\u2019entreprise.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-8147\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-8147\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Encourager l'\u00e9change<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-8147\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-8147\"><p id=\"encourager-lechange\" class=\"bloc\">Filiale de Danone au Ghana, Fan Milk, le sp\u00e9cialiste ouest-africain des glaces et des jus, a fait confiance \u00e0 Boccard pour augmenter la capacit\u00e9 de production de son usine de cr\u00e8mes glac\u00e9es gr\u00e2ce \u00e0 l\u2019implantation d\u2019une nouvelle ligne de production de yaourts.<\/p>\n\n<div class=\"carrebleu\">\n<p class=\"citation\">Se r\u00e9unir est un d\u00e9but, rester ensemble est un progr\u00e8s, travailler ensemble est la r\u00e9ussite<\/p>\n\n<\/div>\n<div class=\"imge_6\"><\/div>\n<p class=\"bloc\">Face \u00e0 l\u2019ampleur du projet (8 400 heures d&rsquo;ing\u00e9nierie, 7 300 heures d&rsquo;automatisation, 4 000 heures de pr\u00e9fabrication en atelier, 5 300 heures de d\u00e9marrage et suivi de production, 2 000 heures de supervision sur le terrain et 21 000 heures d\u2019installation sur site) 5 Business Units se sont mobilis\u00e9es tambour battant : Boccard Process Vessels a fabriqu\u00e9 les r\u00e9servoirs, Boccard Polska a pris en charge l\u2019exp\u00e9dition de mat\u00e9riel, Boccard C\u00f4te d\u2019Ivoire a effectu\u00e9 l\u2019installation sur site avec le concours de Boccard Russie qui a d\u00e9p\u00each\u00e9 un technicien de terrain.\n\nLa Business Unit Boccard Food &amp; Beverages a, quant \u00e0 elle, coordonn\u00e9 l\u2019ensemble des interventions et pilot\u00e9 la gestion du projet dans son int\u00e9gralit\u00e9. Un team spirit que n\u2019a pas manqu\u00e9 de saluer Patrick Kers, responsable projets de Danone en Afrique.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-942e6b0 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"942e6b0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-78e3fb4\" data-id=\"78e3fb4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4d6ae1 elementor-widget elementor-widget-heading\" data-id=\"e4d6ae1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vous avez un projet ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-35f0555\" data-id=\"35f0555\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d9ac681 elementor-align-right elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"d9ac681\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.boccard.com\/fr\/contact-form\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49a3d65 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49a3d65\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-46622b5\" data-id=\"46622b5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-494d768 clair elementor-widget elementor-widget-heading\" data-id=\"494d768\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"lite\">Nos clients<\/span><br \/><span class=\"normal\">Ils nous font <\/span>confiance<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2790545 elementor-hidden-tablet elementor-hidden-mobile\" data-id=\"2790545\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e4dad0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e4dad0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2f261b1\" data-id=\"2f261b1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe47097 clients elementor-widget elementor-widget-image-carousel\" data-id=\"fe47097\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;5&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;slides_to_show_tablet&quot;:&quot;4&quot;,&quot;slides_to_show_mobile&quot;:&quot;2&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Image Carousel\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/08\/Logo_LOre\u2560ual.jpg\" alt=\"Logo_LOre\u2560ual\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/08\/Logo_Alstom-1.jpg\" alt=\"Logo_Alstom-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/08\/Logo_bonduelle.jpg\" alt=\"Logo_bonduelle\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/08\/Logo_EDF-1.jpg\" alt=\"Logo_EDF-1\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/08\/Logo_Voltalia.jpg\" alt=\"Logo_Voltalia\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/08\/Logo_ArcelorMittal.jpg\" alt=\"Logo_ArcelorMittal\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/08\/Logo_AB_InBev.jpg\" alt=\"Logo_AB_InBev\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/08\/Logo_Sanofi.jpg\" alt=\"Logo_Sanofi\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/08\/Logo_Orano.jpg\" alt=\"Logo_Orano\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 sur 10\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/08\/Logo_Danone-1.jpg\" alt=\"Logo_Danone-1\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>L&rsquo;ADN Boccard Nos Valeurs Notre vision Leader des solutions industrielles digitales pleinement int\u00e9gr\u00e9es Bruno &amp; PATRICK BOCCARD Notre mission Nos valeurs Entreprendre avec audace et t\u00e9nacit\u00e9 Pour Joseph Boccard, toute prise d\u2019initiative, si hardie soit elle, n\u2019a qu\u2019une seule issue possible : le succ\u00e8s. Un \u00e9tat d\u2019esprit dont h\u00e9rite son fils Francisque Boccard, qui, en [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":40,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1185","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vision, Missions &amp; Valeurs - Boccard<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.boccard.com\/fr\/adn-boccard\/vision-missions-valeurs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vision, Missions &amp; Valeurs - Boccard\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;ADN Boccard Nos Valeurs Notre vision Leader des solutions industrielles digitales pleinement int\u00e9gr\u00e9es Bruno &amp; PATRICK BOCCARD Notre mission Nos valeurs Entreprendre avec audace et t\u00e9nacit\u00e9 Pour Joseph Boccard, toute prise d\u2019initiative, si hardie soit elle, n\u2019a qu\u2019une seule issue possible : le succ\u00e8s. Un \u00e9tat d\u2019esprit dont h\u00e9rite son fils Francisque Boccard, qui, en [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.boccard.com\/fr\/adn-boccard\/vision-missions-valeurs\/\" \/>\n<meta property=\"og:site_name\" content=\"Boccard\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-04T15:07:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/10\/DSC3897-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.boccard.com\\\/fr\\\/adn-boccard\\\/vision-missions-valeurs\\\/\",\"url\":\"https:\\\/\\\/www.boccard.com\\\/fr\\\/adn-boccard\\\/vision-missions-valeurs\\\/\",\"name\":\"Vision, Missions &amp; Valeurs - Boccard\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.boccard.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.boccard.com\\\/fr\\\/adn-boccard\\\/vision-missions-valeurs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.boccard.com\\\/fr\\\/adn-boccard\\\/vision-missions-valeurs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.boccard.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/DSC3897-scaled-1.jpg\",\"datePublished\":\"2023-08-25T13:29:05+00:00\",\"dateModified\":\"2026-03-04T15:07:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.boccard.com\\\/fr\\\/adn-boccard\\\/vision-missions-valeurs\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.boccard.com\\\/fr\\\/adn-boccard\\\/vision-missions-valeurs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.boccard.com\\\/fr\\\/adn-boccard\\\/vision-missions-valeurs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.boccard.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/DSC3897-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.boccard.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/DSC3897-scaled-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.boccard.com\\\/fr\\\/adn-boccard\\\/vision-missions-valeurs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.boccard.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ADN Boccard\",\"item\":\"https:\\\/\\\/www.boccard.com\\\/fr\\\/adn-boccard\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Vision, Missions &amp; Valeurs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.boccard.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.boccard.com\\\/fr\\\/\",\"name\":\"Boccard\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.boccard.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.boccard.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.boccard.com\\\/fr\\\/#organization\",\"name\":\"Boccard\",\"url\":\"https:\\\/\\\/www.boccard.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.boccard.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.boccard.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/LOGO-BOCCARD-BLEU-SUR-FOND-TRANSPARENT.png\",\"contentUrl\":\"https:\\\/\\\/www.boccard.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/LOGO-BOCCARD-BLEU-SUR-FOND-TRANSPARENT.png\",\"width\":1423,\"height\":333,\"caption\":\"Boccard\"},\"image\":{\"@id\":\"https:\\\/\\\/www.boccard.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/boccard\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vision, Missions &amp; Valeurs - Boccard","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.boccard.com\/fr\/adn-boccard\/vision-missions-valeurs\/","og_locale":"fr_FR","og_type":"article","og_title":"Vision, Missions &amp; Valeurs - Boccard","og_description":"L&rsquo;ADN Boccard Nos Valeurs Notre vision Leader des solutions industrielles digitales pleinement int\u00e9gr\u00e9es Bruno &amp; PATRICK BOCCARD Notre mission Nos valeurs Entreprendre avec audace et t\u00e9nacit\u00e9 Pour Joseph Boccard, toute prise d\u2019initiative, si hardie soit elle, n\u2019a qu\u2019une seule issue possible : le succ\u00e8s. Un \u00e9tat d\u2019esprit dont h\u00e9rite son fils Francisque Boccard, qui, en [&hellip;]","og_url":"https:\/\/www.boccard.com\/fr\/adn-boccard\/vision-missions-valeurs\/","og_site_name":"Boccard","article_modified_time":"2026-03-04T15:07:05+00:00","og_image":[{"width":2560,"height":1709,"url":"https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/10\/DSC3897-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.boccard.com\/fr\/adn-boccard\/vision-missions-valeurs\/","url":"https:\/\/www.boccard.com\/fr\/adn-boccard\/vision-missions-valeurs\/","name":"Vision, Missions &amp; Valeurs - Boccard","isPartOf":{"@id":"https:\/\/www.boccard.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.boccard.com\/fr\/adn-boccard\/vision-missions-valeurs\/#primaryimage"},"image":{"@id":"https:\/\/www.boccard.com\/fr\/adn-boccard\/vision-missions-valeurs\/#primaryimage"},"thumbnailUrl":"https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/10\/DSC3897-scaled-1.jpg","datePublished":"2023-08-25T13:29:05+00:00","dateModified":"2026-03-04T15:07:05+00:00","breadcrumb":{"@id":"https:\/\/www.boccard.com\/fr\/adn-boccard\/vision-missions-valeurs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.boccard.com\/fr\/adn-boccard\/vision-missions-valeurs\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.boccard.com\/fr\/adn-boccard\/vision-missions-valeurs\/#primaryimage","url":"https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/10\/DSC3897-scaled-1.jpg","contentUrl":"https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/10\/DSC3897-scaled-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.boccard.com\/fr\/adn-boccard\/vision-missions-valeurs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.boccard.com\/fr\/"},{"@type":"ListItem","position":2,"name":"ADN Boccard","item":"https:\/\/www.boccard.com\/fr\/adn-boccard\/"},{"@type":"ListItem","position":3,"name":"Vision, Missions &amp; Valeurs"}]},{"@type":"WebSite","@id":"https:\/\/www.boccard.com\/fr\/#website","url":"https:\/\/www.boccard.com\/fr\/","name":"Boccard","description":"","publisher":{"@id":"https:\/\/www.boccard.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.boccard.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.boccard.com\/fr\/#organization","name":"Boccard","url":"https:\/\/www.boccard.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.boccard.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/08\/LOGO-BOCCARD-BLEU-SUR-FOND-TRANSPARENT.png","contentUrl":"https:\/\/www.boccard.com\/wp-content\/uploads\/2023\/08\/LOGO-BOCCARD-BLEU-SUR-FOND-TRANSPARENT.png","width":1423,"height":333,"caption":"Boccard"},"image":{"@id":"https:\/\/www.boccard.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/boccard"]}]}},"_links":{"self":[{"href":"https:\/\/www.boccard.com\/fr\/wp-json\/wp\/v2\/pages\/1185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.boccard.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.boccard.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.boccard.com\/fr\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.boccard.com\/fr\/wp-json\/wp\/v2\/comments?post=1185"}],"version-history":[{"count":34,"href":"https:\/\/www.boccard.com\/fr\/wp-json\/wp\/v2\/pages\/1185\/revisions"}],"predecessor-version":[{"id":86311,"href":"https:\/\/www.boccard.com\/fr\/wp-json\/wp\/v2\/pages\/1185\/revisions\/86311"}],"up":[{"embeddable":true,"href":"https:\/\/www.boccard.com\/fr\/wp-json\/wp\/v2\/pages\/40"}],"wp:attachment":[{"href":"https:\/\/www.boccard.com\/fr\/wp-json\/wp\/v2\/media?parent=1185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}